{"id":634,"count":4,"description":"","link":"https:\/\/dfg-lfa.org\/en\/tag\/ueberschwemmung\/","name":"\u00dcberschwemmung","slug":"ueberschwemmung","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00dcberschwemmung Archive - Franco-German High School Saarbr\u00fccken<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dfg-lfa.org\/en\/tag\/ueberschwemmung\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcberschwemmung Archive - Franco-German High School Saarbr\u00fccken\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dfg-lfa.org\/en\/tag\/ueberschwemmung\/\" \/>\n<meta property=\"og:site_name\" content=\"Franco-German High School Saarbr\u00fccken\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dfg-lfa.org\/wp-content\/uploads\/default-pic.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1134\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@DFGLFA\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/en\\\/tag\\\/ueberschwemmung\\\/\",\"url\":\"https:\\\/\\\/dfg-lfa.org\\\/en\\\/tag\\\/ueberschwemmung\\\/\",\"name\":\"\u00dcberschwemmung Archive - Franco-German High School Saarbr\u00fccken\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/en\\\/tag\\\/ueberschwemmung\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/en\\\/tag\\\/ueberschwemmung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/dfg-lfa.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcberschwemmung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/dfg-lfa.org\\\/en\\\/\",\"name\":\"Franco-German High School Saarbr\u00fccken\",\"description\":\"Einander begegnen \u2013 Avancer ensemble \u2013 We make Europe happen\",\"publisher\":{\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dfg-lfa.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/en\\\/#organization\",\"name\":\"Deutsch-Franz\u00f6sisches Gymnasium Saarbr\u00fccken\",\"url\":\"https:\\\/\\\/dfg-lfa.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dfg-lfa.org\\\/wp-content\\\/uploads\\\/DFG-logo.png\",\"contentUrl\":\"https:\\\/\\\/dfg-lfa.org\\\/wp-content\\\/uploads\\\/DFG-logo.png\",\"width\":200,\"height\":77,\"caption\":\"Deutsch-Franz\u00f6sisches Gymnasium Saarbr\u00fccken\"},\"image\":{\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dfglfa\\\/\",\"https:\\\/\\\/x.com\\\/DFGLFA\",\"https:\\\/\\\/www.instagram.com\\\/dfg_lfa_saarbruecken\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCoxV4_gnJ3blV1U7iOjCV7w\\\/\",\"https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/Deutsch-Franz\u00f6sisches_Gymnasium_in_Saarbr\u00fccken\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00dcberschwemmung Archive - Franco-German High School Saarbr\u00fccken","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dfg-lfa.org\/en\/tag\/ueberschwemmung\/","og_locale":"en_US","og_type":"article","og_title":"\u00dcberschwemmung Archive - Franco-German High School Saarbr\u00fccken","og_url":"https:\/\/dfg-lfa.org\/en\/tag\/ueberschwemmung\/","og_site_name":"Franco-German High School Saarbr\u00fccken","og_image":[{"width":1134,"height":640,"url":"https:\/\/dfg-lfa.org\/wp-content\/uploads\/default-pic.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@DFGLFA","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/dfg-lfa.org\/en\/tag\/ueberschwemmung\/","url":"https:\/\/dfg-lfa.org\/en\/tag\/ueberschwemmung\/","name":"\u00dcberschwemmung Archive - Franco-German High School Saarbr\u00fccken","isPartOf":{"@id":"https:\/\/dfg-lfa.org\/en\/#website"},"breadcrumb":{"@id":"https:\/\/dfg-lfa.org\/en\/tag\/ueberschwemmung\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/dfg-lfa.org\/en\/tag\/ueberschwemmung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dfg-lfa.org\/en\/"},{"@type":"ListItem","position":2,"name":"\u00dcberschwemmung"}]},{"@type":"WebSite","@id":"https:\/\/dfg-lfa.org\/en\/#website","url":"https:\/\/dfg-lfa.org\/en\/","name":"Franco-German High School Saarbr\u00fccken","description":"Einander begegnen \u2013 Avancer ensemble \u2013 We make Europe happen","publisher":{"@id":"https:\/\/dfg-lfa.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dfg-lfa.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dfg-lfa.org\/en\/#organization","name":"Deutsch-Franz\u00f6sisches Gymnasium Saarbr\u00fccken","url":"https:\/\/dfg-lfa.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dfg-lfa.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/dfg-lfa.org\/wp-content\/uploads\/DFG-logo.png","contentUrl":"https:\/\/dfg-lfa.org\/wp-content\/uploads\/DFG-logo.png","width":200,"height":77,"caption":"Deutsch-Franz\u00f6sisches Gymnasium Saarbr\u00fccken"},"image":{"@id":"https:\/\/dfg-lfa.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dfglfa\/","https:\/\/x.com\/DFGLFA","https:\/\/www.instagram.com\/dfg_lfa_saarbruecken\/","https:\/\/www.youtube.com\/channel\/UCoxV4_gnJ3blV1U7iOjCV7w\/","https:\/\/de.wikipedia.org\/wiki\/Deutsch-Franz\u00f6sisches_Gymnasium_in_Saarbr\u00fccken"]}]}},"_links":{"self":[{"href":"https:\/\/dfg-lfa.org\/en\/wp-json\/wp\/v2\/tags\/634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dfg-lfa.org\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/dfg-lfa.org\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/dfg-lfa.org\/en\/wp-json\/wp\/v2\/posts?tags=634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}