{"id":33526,"date":"2017-01-06T21:05:27","date_gmt":"2017-01-06T20:05:27","guid":{"rendered":"http:\/\/dfg-lfa.org\/?p=33526"},"modified":"2020-10-21T13:38:59","modified_gmt":"2020-10-21T11:38:59","slug":"lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken","status":"publish","type":"post","link":"https:\/\/dfg-lfa.org\/fr\/2017\/01\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\/","title":{"rendered":"Les \u00e9l\u00e8ves de Premi\u00e8re ES en visite dans les locaux de la Bundesbank de Sarrebruck"},"content":{"rendered":"<p><a href=\"https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-33530 alignleft\" src=\"https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-300x169.jpg\" alt=\"es \u00e9l\u00e8ves de Premi\u00e8re ES en visite dans les locaux de la Bundesbank de Sarrebruck\" width=\"300\" height=\"169\" srcset=\"https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-300x169.jpg 300w, https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-150x84.jpg 150w, https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-768x432.jpg 768w, https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-590x332.jpg 590w, https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Comprendre les objectifs et les moyens de la politique mon\u00e9taire de la BCE, mais aussi quel r\u00f4le la Bundesbank joue-t-telle dans le syst\u00e8me bancaire ? Voil\u00e0 certains des th\u00e8mes abord\u00e9s lors de la conf\u00e9rence \u00e0 laquelle ont assist\u00e9e les \u00e9l\u00e8ves de Premi\u00e8re ES.<\/p>\n<p><a href=\"https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-33530\" src=\"https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-300x169.jpg\" alt=\"es \u00e9l\u00e8ves de Premi\u00e8re ES en visite dans les locaux de la Bundesbank de Sarrebruck\" width=\"300\" height=\"169\" srcset=\"https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-300x169.jpg 300w, https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-150x84.jpg 150w, https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-768x432.jpg 768w, https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-590x332.jpg 590w, https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>En effet, dans le cadre du cours de sciences \u00e9conomiques et sociales, les \u00e9l\u00e8ves de Premi\u00e8re ES, chaleureusement accueillis le 13 d\u00e9cembre 2016 dans la salle de r\u00e9union des locaux de la Bundesbank de Sarrebruck, ont eu la chance d\u2019assister \u00e0 une conf\u00e9rence donn\u00e9e par Frau Kuhn sur le th\u00e8me de<br \/>\nLa politique mon\u00e9taire de la BCE.<\/p>\n<p><a href=\"https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-33531\" src=\"https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-3-300x169.jpg\" alt=\"es \u00e9l\u00e8ves de Premi\u00e8re ES en visite dans les locaux de la Bundesbank de Sarrebruck\" width=\"300\" height=\"169\" srcset=\"https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-3-300x169.jpg 300w, https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-3-150x84.jpg 150w, https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-3-768x432.jpg 768w, https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-3-590x332.jpg 590w, https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-3.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>R\u00e9alis\u00e9e en langue allemande, cette exp\u00e9rience a \u00e9galement permis aux \u00e9l\u00e8ves d\u2019approfondir leurs connaissances du sujet d\u00e9j\u00e0 trait\u00e9 en cours en langue fran\u00e7aise.<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left shariff-buttonstretch\" style=\"display:none\"><ul class=\"shariff-buttons theme-white orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fdfg-lfa.org%2Ffr%2F2017%2F01%2Flasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken%2F\" title=\"Envoyer par Facebook\" aria-label=\"Envoyer par Facebook\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#3b5998\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#3b5998\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#3b5998\">partager<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fdfg-lfa.org%2Ffr%2F2017%2F01%2Flasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken%2F%20Les%20%C3%A9l%C3%A8ves%20de%20Premi%C3%A8re%20ES%20en%20visite%20dans%20les%20locaux%20de%20la%20Bundesbank%20de%20Sarrebruck\" title=\"Envoyer par Whatsapp\" aria-label=\"Envoyer par Whatsapp\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#34af23\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#34af23\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#34af23\">partager<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Les%20%C3%A9l%C3%A8ves%20de%20Premi%C3%A8re%20ES%20en%20visite%20dans%20les%20locaux%20de%20la%20Bundesbank%20de%20Sarrebruck%20https%3A%2F%2Fdfg-lfa.org%2Ffr%2F2017%2F01%2Flasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken%2F\" title=\"Envoyer par Threema\" aria-label=\"Envoyer par Threema\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#1f1f1f\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#1f1f1f\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#1f1f1f\">partager<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Les%20%C3%A9l%C3%A8ves%20de%20Premi%C3%A8re%20ES%20en%20visite%20dans%20les%20locaux%20de%20la%20Bundesbank%20de%20Sarrebruck https%3A%2F%2Fdfg-lfa.org%2Ffr%2F2017%2F01%2Flasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken%2F\" title=\"Envoyer par Mastodon\" aria-label=\"Envoyer par Mastodon\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#6364FF\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#6364FF\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\" style=\"color:#6364FF\">partager<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button mailto shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"mailto:?body=https%3A%2F%2Fdfg-lfa.org%2Ffr%2F2017%2F01%2Flasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken%2F&subject=Les%20%C3%A9l%C3%A8ves%20de%20Premi%C3%A8re%20ES%20en%20visite%20dans%20les%20locaux%20de%20la%20Bundesbank%20de%20Sarrebruck\" title=\"Envoyer par courriel\" aria-label=\"Envoyer par courriel\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#999; color:#999\"><span class=\"shariff-icon\" style=\"fill:#999\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#999\" d=\"M32 12.7v14.2q0 1.2-0.8 2t-2 0.9h-26.3q-1.2 0-2-0.9t-0.8-2v-14.2q0.8 0.9 1.8 1.6 6.5 4.4 8.9 6.1 1 0.8 1.6 1.2t1.7 0.9 2 0.4h0.1q0.9 0 2-0.4t1.7-0.9 1.6-1.2q3-2.2 8.9-6.1 1-0.7 1.8-1.6zM32 7.4q0 1.4-0.9 2.7t-2.2 2.2q-6.7 4.7-8.4 5.8-0.2 0.1-0.7 0.5t-1 0.7-0.9 0.6-1.1 0.5-0.9 0.2h-0.1q-0.4 0-0.9-0.2t-1.1-0.5-0.9-0.6-1-0.7-0.7-0.5q-1.6-1.1-4.7-3.2t-3.6-2.6q-1.1-0.7-2.1-2t-1-2.5q0-1.4 0.7-2.3t2.1-0.9h26.3q1.2 0 2 0.8t0.9 2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#999\">courriel<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Datenschutz-Infos\" aria-label=\"Datenschutz-Infos\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#999; color:#999\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#999\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Comprendre les objectifs et les moyens de la politique mon\u00e9taire de la BCE, mais aussi quel r\u00f4le la Bundesbank joue-t-telle dans le syst\u00e8me bancaire ? Voil\u00e0 certains des th\u00e8mes abord\u00e9s lors de la conf\u00e9rence \u00e0 laquelle ont assist\u00e9e les \u00e9l\u00e8ves de Premi\u00e8re ES. En effet, dans le cadre du cours &hellip;<\/p>\n","protected":false},"author":2,"featured_media":33529,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[3,54],"tags":[464],"class_list":["post-33526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schule-aktuell","category-wirtschaftswissenschaft","tag-bundesbank"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les \u00e9l\u00e8ves de Premi\u00e8re ES en visite dans les locaux de la Bundesbank de Sarrebruck - Lyc\u00e9e Franco-Allemand de Sarrebruck<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dfg-lfa.org\/fr\/2017\/01\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les \u00e9l\u00e8ves de Premi\u00e8re ES en visite dans les locaux de la Bundesbank de Sarrebruck - Lyc\u00e9e Franco-Allemand de Sarrebruck\" \/>\n<meta property=\"og:description\" content=\"Comprendre les objectifs et les moyens de la politique mon\u00e9taire de la BCE, mais aussi quel r\u00f4le la Bundesbank joue-t-telle dans le syst\u00e8me bancaire ? Voil\u00e0 certains des th\u00e8mes abord\u00e9s lors de la conf\u00e9rence \u00e0 laquelle ont assist\u00e9e les \u00e9l\u00e8ves de Premi\u00e8re ES. En effet, dans le cadre du cours &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dfg-lfa.org\/fr\/2017\/01\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\/\" \/>\n<meta property=\"og:site_name\" content=\"Lyc\u00e9e Franco-Allemand de Sarrebruck\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dfglfa\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-06T20:05:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-21T11:38:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administrator\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DFGLFA\" \/>\n<meta name=\"twitter:site\" content=\"@DFGLFA\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrator\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/2017\\\/01\\\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/2017\\\/01\\\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\\\/\"},\"author\":{\"name\":\"Administrator\",\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/#\\\/schema\\\/person\\\/a8fe67fb1ec6d85c85d21daf2d68fa69\"},\"headline\":\"Les \u00e9l\u00e8ves de Premi\u00e8re ES en visite dans les locaux de la Bundesbank de Sarrebruck\",\"datePublished\":\"2017-01-06T20:05:27+00:00\",\"dateModified\":\"2020-10-21T11:38:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/2017\\\/01\\\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\\\/\"},\"wordCount\":272,\"publisher\":{\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/2017\\\/01\\\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dfg-lfa.org\\\/wp-content\\\/uploads\\\/1ES-Bundesbank-2.jpg\",\"keywords\":[\"Bundesbank\"],\"articleSection\":[\"Actualit\u00e9s\",\"SES\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/2017\\\/01\\\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\\\/\",\"url\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/2017\\\/01\\\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\\\/\",\"name\":\"Les \u00e9l\u00e8ves de Premi\u00e8re ES en visite dans les locaux de la Bundesbank de Sarrebruck - Lyc\u00e9e Franco-Allemand de Sarrebruck\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/2017\\\/01\\\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/2017\\\/01\\\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dfg-lfa.org\\\/wp-content\\\/uploads\\\/1ES-Bundesbank-2.jpg\",\"datePublished\":\"2017-01-06T20:05:27+00:00\",\"dateModified\":\"2020-10-21T11:38:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/2017\\\/01\\\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/2017\\\/01\\\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/2017\\\/01\\\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dfg-lfa.org\\\/wp-content\\\/uploads\\\/1ES-Bundesbank-2.jpg\",\"contentUrl\":\"https:\\\/\\\/dfg-lfa.org\\\/wp-content\\\/uploads\\\/1ES-Bundesbank-2.jpg\",\"width\":1000,\"height\":563,\"caption\":\"es \u00e9l\u00e8ves de Premi\u00e8re ES en visite dans les locaux de la Bundesbank de Sarrebruck\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/2017\\\/01\\\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les \u00e9l\u00e8ves de Premi\u00e8re ES en visite dans les locaux de la Bundesbank de Sarrebruck\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/\",\"name\":\"Lyc\u00e9e Franco-Allemand de Sarrebruck\",\"description\":\"Einander begegnen \u2013 Avancer ensemble \u2013 We make Europe happen\",\"publisher\":{\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/#organization\",\"name\":\"Deutsch-Franz\u00f6sisches Gymnasium Saarbr\u00fccken\",\"url\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dfg-lfa.org\\\/wp-content\\\/uploads\\\/DFG-logo.png\",\"contentUrl\":\"https:\\\/\\\/dfg-lfa.org\\\/wp-content\\\/uploads\\\/DFG-logo.png\",\"width\":200,\"height\":77,\"caption\":\"Deutsch-Franz\u00f6sisches Gymnasium Saarbr\u00fccken\"},\"image\":{\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dfglfa\\\/\",\"https:\\\/\\\/x.com\\\/DFGLFA\",\"https:\\\/\\\/www.instagram.com\\\/dfg_lfa_saarbruecken\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCoxV4_gnJ3blV1U7iOjCV7w\\\/\",\"https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/Deutsch-Franz\u00f6sisches_Gymnasium_in_Saarbr\u00fccken\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dfg-lfa.org\\\/#\\\/schema\\\/person\\\/a8fe67fb1ec6d85c85d21daf2d68fa69\",\"name\":\"Administrator\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les \u00e9l\u00e8ves de Premi\u00e8re ES en visite dans les locaux de la Bundesbank de Sarrebruck - Lyc\u00e9e Franco-Allemand de Sarrebruck","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dfg-lfa.org\/fr\/2017\/01\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\/","og_locale":"fr_FR","og_type":"article","og_title":"Les \u00e9l\u00e8ves de Premi\u00e8re ES en visite dans les locaux de la Bundesbank de Sarrebruck - Lyc\u00e9e Franco-Allemand de Sarrebruck","og_description":"Comprendre les objectifs et les moyens de la politique mon\u00e9taire de la BCE, mais aussi quel r\u00f4le la Bundesbank joue-t-telle dans le syst\u00e8me bancaire ? Voil\u00e0 certains des th\u00e8mes abord\u00e9s lors de la conf\u00e9rence \u00e0 laquelle ont assist\u00e9e les \u00e9l\u00e8ves de Premi\u00e8re ES. En effet, dans le cadre du cours &hellip;","og_url":"https:\/\/dfg-lfa.org\/fr\/2017\/01\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\/","og_site_name":"Lyc\u00e9e Franco-Allemand de Sarrebruck","article_publisher":"https:\/\/www.facebook.com\/dfglfa\/","article_published_time":"2017-01-06T20:05:27+00:00","article_modified_time":"2020-10-21T11:38:59+00:00","og_image":[{"width":1000,"height":563,"url":"https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-2.jpg","type":"image\/jpeg"}],"author":"Administrator","twitter_card":"summary_large_image","twitter_creator":"@DFGLFA","twitter_site":"@DFGLFA","twitter_misc":{"\u00c9crit par":"Administrator","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dfg-lfa.org\/fr\/2017\/01\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\/#article","isPartOf":{"@id":"https:\/\/dfg-lfa.org\/fr\/2017\/01\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\/"},"author":{"name":"Administrator","@id":"https:\/\/dfg-lfa.org\/#\/schema\/person\/a8fe67fb1ec6d85c85d21daf2d68fa69"},"headline":"Les \u00e9l\u00e8ves de Premi\u00e8re ES en visite dans les locaux de la Bundesbank de Sarrebruck","datePublished":"2017-01-06T20:05:27+00:00","dateModified":"2020-10-21T11:38:59+00:00","mainEntityOfPage":{"@id":"https:\/\/dfg-lfa.org\/fr\/2017\/01\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\/"},"wordCount":272,"publisher":{"@id":"https:\/\/dfg-lfa.org\/#organization"},"image":{"@id":"https:\/\/dfg-lfa.org\/fr\/2017\/01\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\/#primaryimage"},"thumbnailUrl":"https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-2.jpg","keywords":["Bundesbank"],"articleSection":["Actualit\u00e9s","SES"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/dfg-lfa.org\/fr\/2017\/01\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\/","url":"https:\/\/dfg-lfa.org\/fr\/2017\/01\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\/","name":"Les \u00e9l\u00e8ves de Premi\u00e8re ES en visite dans les locaux de la Bundesbank de Sarrebruck - Lyc\u00e9e Franco-Allemand de Sarrebruck","isPartOf":{"@id":"https:\/\/dfg-lfa.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dfg-lfa.org\/fr\/2017\/01\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\/#primaryimage"},"image":{"@id":"https:\/\/dfg-lfa.org\/fr\/2017\/01\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\/#primaryimage"},"thumbnailUrl":"https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-2.jpg","datePublished":"2017-01-06T20:05:27+00:00","dateModified":"2020-10-21T11:38:59+00:00","breadcrumb":{"@id":"https:\/\/dfg-lfa.org\/fr\/2017\/01\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/dfg-lfa.org\/fr\/2017\/01\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\/"]]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dfg-lfa.org\/fr\/2017\/01\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\/#primaryimage","url":"https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-2.jpg","contentUrl":"https:\/\/dfg-lfa.org\/wp-content\/uploads\/1ES-Bundesbank-2.jpg","width":1000,"height":563,"caption":"es \u00e9l\u00e8ves de Premi\u00e8re ES en visite dans les locaux de la Bundesbank de Sarrebruck"},{"@type":"BreadcrumbList","@id":"https:\/\/dfg-lfa.org\/fr\/2017\/01\/lasse-premiere-es-zu-besuch-in-der-bundesbank-filiale-saarbruecken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dfg-lfa.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Les \u00e9l\u00e8ves de Premi\u00e8re ES en visite dans les locaux de la Bundesbank de Sarrebruck"}]},{"@type":"WebSite","@id":"https:\/\/dfg-lfa.org\/fr\/#website","url":"https:\/\/dfg-lfa.org\/fr\/","name":"Lyc\u00e9e Franco-Allemand de Sarrebruck","description":"Einander begegnen \u2013 Avancer ensemble \u2013 We make Europe happen","publisher":{"@id":"https:\/\/dfg-lfa.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dfg-lfa.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dfg-lfa.org\/fr\/#organization","name":"Deutsch-Franz\u00f6sisches Gymnasium Saarbr\u00fccken","url":"https:\/\/dfg-lfa.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dfg-lfa.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/dfg-lfa.org\/wp-content\/uploads\/DFG-logo.png","contentUrl":"https:\/\/dfg-lfa.org\/wp-content\/uploads\/DFG-logo.png","width":200,"height":77,"caption":"Deutsch-Franz\u00f6sisches Gymnasium Saarbr\u00fccken"},"image":{"@id":"https:\/\/dfg-lfa.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dfglfa\/","https:\/\/x.com\/DFGLFA","https:\/\/www.instagram.com\/dfg_lfa_saarbruecken\/","https:\/\/www.youtube.com\/channel\/UCoxV4_gnJ3blV1U7iOjCV7w\/","https:\/\/de.wikipedia.org\/wiki\/Deutsch-Franz\u00f6sisches_Gymnasium_in_Saarbr\u00fccken"]},{"@type":"Person","@id":"https:\/\/dfg-lfa.org\/#\/schema\/person\/a8fe67fb1ec6d85c85d21daf2d68fa69","name":"Administrator"}]}},"_links":{"self":[{"href":"https:\/\/dfg-lfa.org\/fr\/wp-json\/wp\/v2\/posts\/33526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dfg-lfa.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dfg-lfa.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dfg-lfa.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dfg-lfa.org\/fr\/wp-json\/wp\/v2\/comments?post=33526"}],"version-history":[{"count":0,"href":"https:\/\/dfg-lfa.org\/fr\/wp-json\/wp\/v2\/posts\/33526\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dfg-lfa.org\/fr\/wp-json\/wp\/v2\/media\/33529"}],"wp:attachment":[{"href":"https:\/\/dfg-lfa.org\/fr\/wp-json\/wp\/v2\/media?parent=33526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dfg-lfa.org\/fr\/wp-json\/wp\/v2\/categories?post=33526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dfg-lfa.org\/fr\/wp-json\/wp\/v2\/tags?post=33526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}